{"id":1230,"date":"2015-03-03T03:13:44","date_gmt":"2015-03-03T02:13:44","guid":{"rendered":"https:\/\/www.interor.fr\/actualites\/?p=1230"},"modified":"2015-03-03T20:02:02","modified_gmt":"2015-03-03T19:02:02","slug":"cotation-de-lor-la-chine-veut-lancer-son-propre-systeme-de-fixation","status":"publish","type":"post","link":"https:\/\/www.interor.fr\/actualites\/cotation-de-lor-la-chine-veut-lancer-son-propre-systeme-de-fixation\/","title":{"rendered":"Cotation de l\u2019or : la chine veut lancer son propre syst\u00e8me de fixation"},"content":{"rendered":"<p>La Chine pense fortement \u00e0 lancer son syst\u00e8me de fixation du prix de l\u2019or en 2015 qui pourrait \u00eatre bas\u00e9 sur une bourse de valeurs de la <a title=\"cotation de l'or\" href=\"http:\/\/www.interor.fr\/cotation_de_l_or.html\" target=\"_blank\">cotation de l&rsquo;or<\/a> en concurren\u00e7ant celui du \u00ab\u00a0London Gold Fix\u00a0\u00bb d\u2019apr\u00e8s certaines sources familiaris\u00e9es sur le sujet. C\u2019est un pas naturel pour la Chine qui est le second plus important consommateur d\u2019or du monde apr\u00e8s l\u2019Inde, \u00e0 poss\u00e9der une plus importante influence sur la fixation de la cotation de l\u2019or \u00e0 un niveau global.<\/p>\n<p>L\u2019indice du prix de l\u2019or chinois s\u2019orienterait vers un contrat d\u2019unit\u00e9s d\u2019or de 1 kilogramme et qui serait lanc\u00e9 par le \u00ab\u00a0Shanghai Gold Exchange\u00a0\u00bb.<\/p>\n<p>Comme nous le savons d\u00e9j\u00e0, la Chine est le producteur minier le plus important du monde de l\u2019or et avec raison, elle pense qu\u2019elle est en droit \u00e0 avoir plus d\u2019influence sur le prix de l\u2019or mondial apr\u00e8s les r\u00e9cents scandales de manipulation du prix de l\u2019or au \u00ab\u00a0London Gold Fix\u00a0\u00bb.<\/p>\n<p>Si l\u2019indice du prix de l\u2019or chinois a du succ\u00e8s, ce serait un s\u00e9rieux rival pour le \u00ab\u00a0London Gold Fix\u00a0\u00bb qui est utilis\u00e9 dans le monde entier par des entreprises mini\u00e8res d\u2019or, des raffineries et des banques centrales pour n\u00e9gocier des inventaires et des contrats sur l\u2019or s\u2019ils existent encore en parall\u00e8le.<\/p>\n<p>\u00ab Nous avons besoin d\u2019un indice pour les producteurs miniers chinois et pour les fournisseurs \u00e9trangers du march\u00e9. Cet indice du prix de l\u2019or, en parti en renminbi, peut \u00eatre compl\u00e9mentaire au dollar du Gold Fix de Londres\u00a0\u00bb selon une source chinoise.<\/p>\n<p>La cotation de l\u2019or chinois se n\u00e9gocierait tous les jours pendant quelques minutes pour r\u00e9aliser un processus transparent et la bourse de l\u2019or ex\u00e9cuterait tous les ordres.<\/p>\n<p>Des limites pour la cr\u00e9ation d\u2019un indice du prix de l\u2019or chinois<\/p>\n<p>Une des barri\u00e8res pour l\u2019acceptation du yuan \u00e0 niveau global est qu\u2019il n\u2019est pas totalement convertible sur tous les march\u00e9s. Une autre source et une banque de l\u2019or cr\u00e9atrice de march\u00e9 la Bullion Bank ont indiqu\u00e9 que la n\u00e9gociation et la liquidation pourraient s\u2019effectuer dans des centres offshore en yuans afin de permettre aux banques \u00e9trang\u00e8res et aux fournisseurs de participer \u00e0 la r\u00e9alisation de l\u2019indice du prix de l\u2019or chinois bien qu\u2019on s\u2019attend \u00e0 ce que seulement des entreprises chinoises y participent au d\u00e9but.<\/p>\n<p>Le \u00ab\u00a0Shanghai Gold Exchange\u00a0\u00bb a cr\u00e9\u00e9 une unit\u00e9 internationale pour sa bourse de l\u2019or en septembre 2014 dans une zone franche de Shanghai qui permet aux \u00e9trangers de n\u00e9gocier des contrats sur l\u2019or en Yuans la premi\u00e8re fois.<\/p>\n<p>Qu\u2019est-ce que tout cela signifiera pour le march\u00e9 de l\u2019or global\u00a0? Est-ce un autre puzzle qui est en train de tomber pour positionner l\u2019axe Russie et Chine dans le but de cr\u00e9er un nouveau mod\u00e8le mon\u00e9taire global\u00a0?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Chine pense fortement \u00e0 lancer son syst\u00e8me de fixation du prix de l\u2019or en 2015 qui pourrait \u00eatre bas\u00e9 sur une bourse de valeurs de la cotation de l&rsquo;or en concurren\u00e7ant celui du \u00ab\u00a0London Gold Fix\u00a0\u00bb d\u2019apr\u00e8s certaines sources familiaris\u00e9es sur le sujet. C\u2019est un pas naturel pour la Chine qui est le second &hellip; <a href=\"https:\/\/www.interor.fr\/actualites\/cotation-de-lor-la-chine-veut-lancer-son-propre-systeme-de-fixation\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Cotation de l\u2019or : la chine veut lancer son propre syst\u00e8me de fixation<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":0,"footnotes":""},"categories":[1],"tags":[10],"class_list":["post-1230","post","type-post","status-publish","format-standard","hentry","category-cours-or","tag-cotation-de-lor"],"_links":{"self":[{"href":"https:\/\/www.interor.fr\/actualites\/wp-json\/wp\/v2\/posts\/1230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.interor.fr\/actualites\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.interor.fr\/actualites\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.interor.fr\/actualites\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.interor.fr\/actualites\/wp-json\/wp\/v2\/comments?post=1230"}],"version-history":[{"count":0,"href":"https:\/\/www.interor.fr\/actualites\/wp-json\/wp\/v2\/posts\/1230\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.interor.fr\/actualites\/wp-json\/wp\/v2\/media?parent=1230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.interor.fr\/actualites\/wp-json\/wp\/v2\/categories?post=1230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.interor.fr\/actualites\/wp-json\/wp\/v2\/tags?post=1230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}